{"id":1010,"date":"2011-09-09T05:55:00","date_gmt":"2011-09-09T05:55:00","guid":{"rendered":"https:\/\/blog.chbworld.net\/index.php\/2011\/09\/09\/der-erste-tag-3\/"},"modified":"2025-02-01T23:50:23","modified_gmt":"2025-02-01T22:50:23","slug":"der-erste-tag-3","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2011\/09\/09\/der-erste-tag-3\/","title":{"rendered":"Der erste Tag"},"content":{"rendered":"<p align=\"justify\">Das Wetter ist unglaublich: Keinerlei Morgennebel, keine Wolke den ganzen Tag in Sicht und wirklich warme Temperaturen. Wir konnten das nur bedingt genie\u00dfen, weil doch viel umger\u00e4umt werden will. Neben Umr\u00e4umen und ersten Eink\u00e4ufen blieb noch genug Zeit f\u00fcr den obligaten Strandspaziergang.<\/p>\n<p align=\"justify\">Wie jedes Jahr frage ich mich, wer sich so ein teures Haus mit Blick auf die Promenade kauft. Hier nun ein tats\u00e4chliches Beispiel: 20 Millionen Dollar soll es gekostet haben. Garten hat man daf\u00fcr keinen:<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2011\/09\/P1050209_re25255B225255D.jpg\" width=\"1024\" height=\"768\"><\/p>\n<p align=\"justify\">Man glaubt mir auch nicht, da\u00df alle H\u00e4user hier aus Holz sind. Auch das vom vorigen Bild. In der N\u00e4he wird ein Haus gerade neu gebaut, da kann man es sich ansehen:<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2011\/09\/P1050210_re25255B225255D.jpg\" width=\"1024\" height=\"611\"><\/p>\n<p align=\"justify\">Die Promenade hei\u00dft \u00fcbrigens The Strand. Die verschiedenen Hausnummern sind immer wieder sehr h\u00fcbsch gestaltet:<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2011\/09\/P1050213_re25255B225255D.jpg\" width=\"1024\" height=\"598\"><\/p>\n<p align=\"justify\">Die schon \u00f6fter gezeigte Surferstatue ist ohne Sonnenuntergang zwar nicht so h\u00fcbsch und romantisch, daf\u00fcr sieht man die Volleyballfelder im Hintergrund:<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2011\/09\/P1050220_re25255B225255D.jpg\" width=\"1024\" height=\"768\"><\/p>\n<p align=\"justify\">Die k\u00fchle Brise vom Meer war heute sehr gut, denn ohne w\u00e4re es ziemlich sicher hitzig geworden. Trotzdem sah man niemanden im Wasser. Das hatte zwei Gr\u00fcnde: Zum einen gab es heute b\u00f6se <a href=\"http:\/\/de.wikipedia.org\/wiki\/Brandungsr%C3%BCckstrom\">Rip-Currents<\/a> und zum anderen war das Wasser vorwiegend f\u00fcr Inuit geeignet: 18\u00b0C (laut Aushang am Pier). Da Joggen sehr in ist und die Leute hier auch am fr\u00fchen Nachmittag joggen wollen, haben wir jede Menge heftig schwitzender Jogger getroffen. \u2018Selbst schuld\u2019 kann ich da nur sagen, hat ja keiner gesagt, da\u00df man am fr\u00fchen Nachmittag in der prallen Sonne joggen soll.<\/p>\n<p align=\"justify\">Die Blumen vertragen offensichtlich dieses Wetter, denn sie haben sich nicht beim Bl\u00fchen st\u00f6ren lassen:<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2011\/09\/P1050222_re25255B225255D.jpg\" width=\"1024\" height=\"790\"><\/p>\n<p align=\"justify\">Zum Abschlu\u00df noch ein weiteres Haus, bevor wir weiter shoppen gingen und unser Freund sich wieder seiner Arbeit zugewendet hat:<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2011\/09\/P1050223_re25255B225255D.jpg\" width=\"1024\" height=\"768\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Wetter ist unglaublich: Keinerlei Morgennebel, keine Wolke den ganzen Tag in Sicht und wirklich warme Temperaturen. Wir konnten das nur bedingt genie\u00dfen, weil doch viel umger\u00e4umt werden will. Neben Umr\u00e4umen und ersten Eink\u00e4ufen blieb noch genug Zeit f\u00fcr den obligaten Strandspaziergang. Wie jedes Jahr frage ich mich, wer sich so ein teures Haus mit Blick auf die Promenade kauft. Hier nun ein tats\u00e4chliches Beispiel: 20 Millionen Dollar soll es gekostet haben. Garten hat man daf\u00fcr keinen: Man glaubt mir auch nicht, da\u00df alle H\u00e4user hier aus Holz sind. Auch das vom vorigen Bild. In der N\u00e4he wird ein Haus<\/p>\n","protected":false},"author":1,"featured_media":35339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aroundtheworld"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/1010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=1010"}],"version-history":[{"count":3,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/1010\/revisions"}],"predecessor-version":[{"id":35340,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/1010\/revisions\/35340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/35339"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=1010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=1010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=1010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}