{"id":19342,"date":"2020-12-29T19:55:00","date_gmt":"2020-12-29T18:55:00","guid":{"rendered":"https:\/\/blog.chbworld.net\/index.php\/2020\/12\/29\/kurzrunde-mit-gatsch\/"},"modified":"2025-02-01T19:53:39","modified_gmt":"2025-02-01T18:53:39","slug":"kurzrunde-mit-gatsch","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2020\/12\/29\/kurzrunde-mit-gatsch\/","title":{"rendered":"Kurzrunde mit Gatsch"},"content":{"rendered":"<p align=\"justify\">Also da konnte ich mich jetzt echt nicht beschweren: Wer h\u00e4tte gedacht, da\u00df ich am 29 Dezember (also zwischen Weihnachten und Silvester) no auf eine Fahrradrunde komme?!? Ok, wenn man sich jetzt die Runde anschaut, ist es eine sehr kleine Runde geworden, aber da war der Gatsch daran Schuld. Es fing super-sonnig und toll an:<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2020\/12\/1sPbq0e-AsGdbVgpc4g7HLu0C5puvOdAE.jpg\" width=\"1024\" height=\"768\"> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2020\/12\/1_rsaJN1-LsrrlYsidcbEKmjUWsgKWaI1.jpg\" width=\"1024\" height=\"768\"><\/p>\n<p align=\"justify\">Am Plateau war es noch ganz ok, aber der Weg rauf zum Wald war dann aufgrund des Gatsches ein no-go. Also direkt durch den Wald runter, aber auch das war mehr ein Rutschen denn ein Fahren.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2020\/12\/1lQzn6ez3prCkwQ4beWOzsCEJIrjvg-zV.jpg\" width=\"1024\" height=\"768\"> <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2020\/12\/1Qw-RKGUh9ghnEH3zzRDhT4GvoTpzu_F8.jpg\" width=\"768\" height=\"1024\"><\/p>\n<p align=\"justify\">Aber trotzdem war es \u00fcberraschend die extrem sp\u00e4teste Runde des Jahres (und das auch noch mit Sonne)!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Also da konnte ich mich jetzt echt nicht beschweren: Wer h\u00e4tte gedacht, da\u00df ich am 29 Dezember (also zwischen Weihnachten und Silvester) no auf eine Fahrradrunde komme?!? Ok, wenn man sich jetzt die Runde anschaut, ist es eine sehr kleine Runde geworden, aber da war der Gatsch daran Schuld. Es fing super-sonnig und toll an: Am Plateau war es noch ganz ok, aber der Weg rauf zum Wald war dann aufgrund des Gatsches ein no-go. Also direkt durch den Wald runter, aber auch das war mehr ein Rutschen denn ein Fahren. Aber trotzdem war es \u00fcberraschend die extrem sp\u00e4teste Runde<\/p>\n","protected":false},"author":1,"featured_media":25843,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-19342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bike"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/19342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=19342"}],"version-history":[{"count":1,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/19342\/revisions"}],"predecessor-version":[{"id":25847,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/19342\/revisions\/25847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/25843"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=19342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=19342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=19342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}