{"id":21663,"date":"2024-10-23T13:52:34","date_gmt":"2024-10-23T12:52:34","guid":{"rendered":"https:\/\/blog.chbworld.net\/?p=21663"},"modified":"2024-12-30T23:58:02","modified_gmt":"2024-12-30T22:58:02","slug":"brisbane-tag-1","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2024\/10\/23\/brisbane-tag-1\/","title":{"rendered":"Brisbane &ndash; Tag 1"},"content":{"rendered":"<p align=\"justify\">Brisbane hat \u00fcberraschend wenige touristische Attraktionen und noch weniger, die man mit einem Hochdachauto erreichen kann.<\/p>\n<p> <iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=164Z6GnxrLy8OIDouu8zNg34M3eJUlvg&amp;ehbc=2E312F\" width=\"640\" height=\"480\"><\/iframe>  <\/p>\n<p align=\"justify\">Wir sind daher heute zum Automuseum gefahren. Quer durch die Stadt und mit Stau. Da pr\u00e4sentiert sich Brisbane nicht von der sch\u00f6nstens Seite. Die Autobahnen sind auch sehr kreativ auf kleinem Raum gebaut, sehr eng, Tunneln und Br\u00fccken. Daf\u00fcr f\u00e4hrt man nur 80km\/h.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_092802\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_092802.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Man findet unterwegs auch nicht mal schnell was zu essen. Das ist hier konzentriert auf Einkaufszentren und Rastst\u00e4tten. Wir haben daher obwohl schon auf surface roads unterwegs eine Rastst\u00e4tte besucht, um nicht hungrig ins Museum zu gehen. Da kam ich zu einem Perser und habe einen sehr interessanten Lamm-Kebab bekommen. Nicht schlecht. Die Parkpl\u00e4tze beim Automuseum sind wieder Garagen, es gab dann doch 2 Pl\u00e4tze f\u00fcr unser Hochdach. Parken mit dem Ding ist immer spannend. Das Museum ist \u00fcberraschend klein. Und daf\u00fcr ganz sch\u00f6n teuer. Aktuell haben sie die Ausstellung von Kleinfahrzeugen. Das beginnt mit schwedischen Mopeds.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_101824\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_101824.jpg\" width=\"768\" height=\"1024\" \/><\/p>\n<p align=\"justify\">Geht \u00fcber Gogfomobile\u2026<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_102008\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_102008.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">\u2026 und landet bei Morris und Rover Minis. Da haben wir uns das Entstehungsvideo des Morris angesehen. Was f\u00fcr ein Weltwunder. Sicherheit hat da noch keiner Nachgefragt.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_102252\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_102252.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Der Rest der kleinen Halle ist dann auch schnell durch.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_105249\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_105249.jpg\" width=\"768\" height=\"1024\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_105549\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_105549.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_105751\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_105751.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_110518\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_110518.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Weiter \u00fcber spannende Stra\u00dfen, Br\u00fccken und Tunnel ging es zum botanischen Garten. Der City Garten am Flu\u00df war f\u00fcr uns mit Hochdach nicht wirklich erreichbar. Die \u00d6ffis sind mit 50 Cent pro Fahrt oder 1.50 f\u00fcr ein Tagesticket sehr billig, aber die Schnellbahn f\u00e4hrt im besten Fall einmal pro Stunde.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_112415\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_112415.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_112831\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_112831.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_112902\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_112902.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Man kann den botanischen Garten mit dem Auto umrunden. Viel stehenbleiben kann man nicht, au\u00dfer am Aussichtspunkt. Ist aber auch \u2013 naja \u2013 eh lieb.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_114316\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_114316.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Dann haben wir unser kleines Monster wieder in einen Autoparkplatz gewuchtet und sind zu Fu\u00df los. Der Garten hat zwar alles vom Glashaus \u00fcber das Farnhaus bis zum Kakteengarten, aber alles ist irgendwie lieblos.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_115952\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_115952.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_120222\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_120222.jpg\" width=\"768\" height=\"1024\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_120508\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_120508.jpg\" width=\"768\" height=\"1024\" \/><\/p>\n<p align=\"justify\">Das Bonsaihaus zeigt einige sehr h\u00fcbsche st\u00fccke, zum Teil schon 1960 gepflanzt.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_120613\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_120613.jpg\" width=\"768\" height=\"1024\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_120646\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_120646.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_120817\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_120817.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Japanischer Garten und Bambustal.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_120954\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_120954.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_123009\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_123009.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Ein paar bl\u00fchende Dinge, ein Vogel zum Best\u00e4uben, die Kakteenecke und der gro\u00dfe Teich.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_123415\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_123415.jpg\" width=\"768\" height=\"1024\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_123747\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_123747.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_124111\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_124111.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_124153\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_124153.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Da gleich neben dem botanischen Garten der Tourist Drive vorbeigeht, sind wir den auch noch schnell gefahren. Der wasserfall war zu gehen und trocken (daher nein danke), der Lookout ist aber genial auf die Stadt. Astrid wollte dort auch eine Kaffee (und Kuchen) Pause einlegen.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_132750_DSC_0001\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_132750_DSC_0001.jpg\" width=\"1024\" height=\"581\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_132824\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_132824.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_133909\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_133909.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_141139\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_141139.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Beim Reden bemerken wir, da\u00df die Techniksachen in Singapur ziemlich teuer waren, aber hier in Australien eigentlich super billig sind. Ich sehe z.B. da\u00df das Xperia 1 VI statt 1309\u20ac in \u00d6sterreich, hier um 899\u20ac zu bekommen ist und ich noch die 10% Steuer bei der Ausreise bekommen w\u00fcrde. Und siehe da, die Micro-Drohne DJI Neo kostet hier gar nur 170\u20ac. In Brisbane gibt es 3 DJI Flagstores. Astrid wollte daher zu einem hinschauen. Das Einkaufszentrum war eh nur eine gute habe Stunde von dem Ausguck entfernt. Nun sind wir Besitzer einer neuen Micro-Drohne. Technikspielecke dazu folgt noch. Das Einkaufszentrum ist auch wirklich h\u00fcbsch und man k\u00f6nnte dort auch super essen.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_155648\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_155648.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_160154\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_160154.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_165425\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_165425.jpg\" width=\"768\" height=\"1024\" \/><\/p>\n<p align=\"justify\">Astrid wollte aber lieber oben im Caf\u00e9 den Sonnenuntergang sehen. Gesagt getan.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20241023_174234\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/20241023_174234.jpg\" width=\"1024\" height=\"768\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/DSC02561_re.jpg\" width=\"1024\" height=\"683\" \/>&#160;<img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2024\/10\/DSC02564_re.jpg\" width=\"1024\" height=\"683\" \/><\/p>\n<p align=\"justify\">Damit blieb nur mehr die gute Stunde durch die Nacht zum Campingplatz. Astrid war \u00fcberraschend munter, sie hat jetzt ein neues Spielzeug.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brisbane hat \u00fcberraschend wenige touristische Attraktionen und noch weniger, die man mit einem Hochdachauto erreichen kann. Wir sind daher heute zum Automuseum gefahren. Quer durch die Stadt und mit Stau. Da pr\u00e4sentiert sich Brisbane nicht von der sch\u00f6nstens Seite. Die Autobahnen sind auch sehr kreativ auf kleinem Raum gebaut, sehr eng, Tunneln und Br\u00fccken. Daf\u00fcr f\u00e4hrt man nur 80km\/h. Man findet unterwegs auch nicht mal schnell was zu essen. Das ist hier konzentriert auf Einkaufszentren und Rastst\u00e4tten. Wir haben daher obwohl schon auf surface roads unterwegs eine Rastst\u00e4tte besucht, um nicht hungrig ins Museum zu gehen. Da kam ich zu<\/p>\n","protected":false},"author":1,"featured_media":21661,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-21663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aroundtheworld"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/21663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=21663"}],"version-history":[{"count":1,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/21663\/revisions"}],"predecessor-version":[{"id":21664,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/21663\/revisions\/21664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/21661"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=21663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=21663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=21663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}