{"id":28,"date":"2023-09-29T03:52:00","date_gmt":"2023-09-29T03:52:00","guid":{"rendered":"https:\/\/blog.chbworld.net\/index.php\/2023\/09\/29\/technikspielecke-camping-gadgets\/"},"modified":"2024-04-19T19:53:39","modified_gmt":"2024-04-19T18:53:39","slug":"technikspielecke-camping-gadgets","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2023\/09\/29\/technikspielecke-camping-gadgets\/","title":{"rendered":"Technikspielecke: Camping Gadgets"},"content":{"rendered":"<p align=\"justify\">Dieses Jahr haben es ein paar Gadgets in die USA geschafft. Hier eine kleine Zusammenfassung:<\/p>\n<ul>\n<li>\n<div align=\"justify\">Amazon hat uns eine Powerbank mit Taschenlampen und Lampenfunktion zum Testen geschenkt. Die ist wirklich brauchbar und ersetzt am Abend v\u00f6llig jede angesteckte Leuchte.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Amazon hat uns eine kleine akkubetriebene Lampe mit Insektenlampenfunktion zum Testen geschenkt. Auch die tut genau was sie soll und zieht die Gelsen brav an. Zu einem Knall beim Vernichten reicht es nicht, sie werden eher langsam geschmort.<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Astrid hat beim neuen Zelt die Angst bekommen, es wird zu warm. Daher haben wir uns einen akkubetriebenen Ventilator mit Licht gekauft. Ein Aufh\u00e4ngehaken ist integriert. Er schafft bei Vollgas zwar nicht die ganze Nacht, aber er ist wirklich leise und bringt genug Luft. Die integrierte Ringlampe erleuchtet auch ein gro\u00dfes Zelt ganz sicher.<\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dieses Jahr haben es ein paar Gadgets in die USA geschafft. Hier eine kleine Zusammenfassung: Amazon hat uns eine Powerbank mit Taschenlampen und Lampenfunktion zum Testen geschenkt. Die ist wirklich brauchbar und ersetzt am Abend v\u00f6llig jede angesteckte Leuchte. Amazon hat uns eine kleine akkubetriebene Lampe mit Insektenlampenfunktion zum Testen geschenkt. Auch die tut genau was sie soll und zieht die Gelsen brav an. Zu einem Knall beim Vernichten reicht es nicht, sie werden eher langsam geschmort. Astrid hat beim neuen Zelt die Angst bekommen, es wird zu warm. Daher haben wir uns einen akkubetriebenen Ventilator mit Licht gekauft. Ein<\/p>\n","protected":false},"author":1,"featured_media":15520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-28","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aroundtheworld"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":1,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"predecessor-version":[{"id":1619,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/28\/revisions\/1619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/15520"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}