{"id":38346,"date":"2025-09-13T18:33:00","date_gmt":"2025-09-13T17:33:00","guid":{"rendered":"https:\/\/blog.chbworld.net\/?p=38346"},"modified":"2025-09-16T18:37:25","modified_gmt":"2025-09-16T17:37:25","slug":"ziegentransport-3","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2025\/09\/13\/ziegentransport-3\/","title":{"rendered":"Ziegentransport 3"},"content":{"rendered":"<p align=\"justify\">Eigentlich ein v\u00f6llig falscher Name, denn wir haben an dem Tag alles andere nur keine Ziegen transportiert. Aber es ging als Ziel zum Bauernhof in St. Peter in der Au, wo wir unsere Ziegen zur Fr\u00fchlingsfrische hingebracht haben. Der Wetterbericht war f\u00fcr die Gegend ziemlich gut mit 7 Stunden Sonne. Also ging es los.<\/p>\n<p align=\"justify\">Ach ja, warum sind wir dorthin gefahren, wenn wir doch keine Ziegen transportieren wollten? Nun, der Bauernhof z\u00fcchtet H\u00fchner verschiedenster Rassen. Und Astrid wollte mehr H\u00fchner. Zun\u00e4chst ging es aber zu Josef-Steiner, da wir quasi dran vorbeigefahren sind und gleich noch Ersatzteile f\u00fcr unser \u00fcberraschendes Zaunprojekt mitgenommen haben. So konnten wir unseren extrem freundlichen und hilfsbereiten Berater einmal pers\u00f6nlich treffen.<\/p>\n<p align=\"justify\">Das mit dem sonnigen Wetter konnten wir leider nicht wirklich best\u00e4tigen, also haben wir uns gleich auf die Suche nach einem netten Gasthof gemacht, weil bei wolkenverhangenen Bergen macht eine Panoramaaussicht nicht so gar arg viel Sinn. Und den kleinen Zoo in Waidhofen\/Ybbs heben wir uns auch f\u00fcr sch\u00f6nes Wetter auf. Das Essen war nicht g\u00fcnstig aber wirklich hervorragend und sie h\u00e4tten sogar eine E-Auto Ladestation gehabt, wenn nicht zwei Idioten davor geparkt h\u00e4tten.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_131816_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_131816_re.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Wir haben von TomTom die romantische Strecke nach St. Peter genommen und hie und da hat sich ein Sonnenstrahl durch die Wolken gebohrt.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_132717_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_132717_re.jpg\" width=\"1024\" height=\"768\" \/> <img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_132752_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_132752_re.jpg\" width=\"1024\" height=\"768\" \/> <img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_133025_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_133025_re.jpg\" width=\"1024\" height=\"760\" \/><\/p>\n<p align=\"justify\">Beim Panoramagasthof war es fast sonnig, da h\u00e4tte es sich ja doch ausgezahlt. Aber egal, so hatten wir mal Abwechslung.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_135749_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_135749_re.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Der Bauernhof mit den H\u00fchnern ist im Mostviertel und an \u00c4pfeln mangelt es dort sicher keinem.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_140253_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_140253_re.jpg\" width=\"1024\" height=\"768\" \/> <img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_140307_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_140307_re.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Am Heimweg mit 8 H\u00fchnern mehr sind wir noch ganz kurz beim Panorama (da wo der Gasthof ist) stehengeblieben. Immer noch echt h\u00fcbsch.<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"20250913_143712_re\" src=\"https:\/\/blog.chbworld.net\/wp-content\/uploads\/2025\/09\/20250913_143712_re.jpg\" width=\"1024\" height=\"768\" \/><\/p>\n<p align=\"justify\">Am Heimweg gab es noch einen kurzen Shoppingstopp beim Lidl, wo wir auch ein bi\u00dfl nachgeladen haben, damit es nicht zu spannend beim Heimfahren wird. Der Tag war daher nicht so sonnig wie versprochen, aber es war wieder nett durch die Gegend zu gurken und das neue Auto macht dabei einfach nur Spa\u00df.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eigentlich ein v\u00f6llig falscher Name, denn wir haben an dem Tag alles andere nur keine Ziegen transportiert. Aber es ging als Ziel zum Bauernhof in St. Peter in der Au, wo wir unsere Ziegen zur Fr\u00fchlingsfrische hingebracht haben. Der Wetterbericht war f\u00fcr die Gegend ziemlich gut mit 7 Stunden Sonne. Also ging es los. Ach ja, warum sind wir dorthin gefahren, wenn wir doch keine Ziegen transportieren wollten? Nun, der Bauernhof z\u00fcchtet H\u00fchner verschiedenster Rassen. Und Astrid wollte mehr H\u00fchner. Zun\u00e4chst ging es aber zu Josef-Steiner, da wir quasi dran vorbeigefahren sind und gleich noch Ersatzteile f\u00fcr unser \u00fcberraschendes Zaunprojekt<\/p>\n","protected":false},"author":1,"featured_media":38345,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-38346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inaustria"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/38346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=38346"}],"version-history":[{"count":1,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/38346\/revisions"}],"predecessor-version":[{"id":38347,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/38346\/revisions\/38347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/38345"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=38346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=38346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=38346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}