{"id":38954,"date":"2025-10-08T19:15:00","date_gmt":"2025-10-08T18:15:00","guid":{"rendered":"https:\/\/blog.chbworld.net\/?p=38954"},"modified":"2025-10-09T20:59:27","modified_gmt":"2025-10-09T19:59:27","slug":"woche-2-2","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2025\/10\/08\/woche-2-2\/","title":{"rendered":"Woche 2"},"content":{"rendered":"<p>Europa ist klein, weil in der zweiten Woche haben wir nur ca. 900km zur\u00fcckgelegt. Aber es waren sch\u00f6ne 900km.<\/p>\n<p> <iframe loading=\"lazy\" height=\"600\" src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1tX9jrJHdLeFLngN58h1sNTGpJ9r-J8I&amp;ehbc=2E312F\" width=\"800\"><\/iframe>   <\/p>\n<p>Wir haben dabei:<\/p>\n<ul>\n<li>die K\u00fcstenstra\u00dfe von Italien kennengelernt<\/li>\n<li>Aix-en-Provence besucht<\/li>\n<li>mehrere sch\u00f6nste D\u00f6rfer Frankreichs kennengelernt<\/li>\n<li>Avignon mit dem Roller erlebt<\/li>\n<li>die gr\u00f6\u00dfte erhaltene Aqu\u00e4duktbr\u00fccke besucht<\/li>\n<li>Nimes mit dem Roller erlebt<\/li>\n<li>einen ganzen Tag in der Camargue unterwegs verbracht<\/li>\n<li>einen Strand am franz\u00f6sischen Mittelmeer besucht<\/li>\n<li>viel Zeit beim Rollern entlang des Canal du Midi verbracht<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Europa ist klein, weil in der zweiten Woche haben wir nur ca. 900km zur\u00fcckgelegt. Aber es waren sch\u00f6ne 900km. Wir haben dabei: die K\u00fcstenstra\u00dfe von Italien kennengelernt Aix-en-Provence besucht mehrere sch\u00f6nste D\u00f6rfer Frankreichs kennengelernt Avignon mit dem Roller erlebt die gr\u00f6\u00dfte erhaltene Aqu\u00e4duktbr\u00fccke besucht Nimes mit dem Roller erlebt einen ganzen Tag in der Camargue unterwegs verbracht einen Strand am franz\u00f6sischen Mittelmeer besucht viel Zeit beim Rollern entlang des Canal du Midi verbracht<\/p>\n","protected":false},"author":1,"featured_media":15516,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-38954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aroundtheworld"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/38954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=38954"}],"version-history":[{"count":3,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/38954\/revisions"}],"predecessor-version":[{"id":38957,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/38954\/revisions\/38957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/15516"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=38954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=38954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=38954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}