{"id":39249,"date":"2025-10-15T22:43:00","date_gmt":"2025-10-15T21:43:00","guid":{"rendered":"https:\/\/blog.chbworld.net\/?p=39249"},"modified":"2025-10-16T19:50:23","modified_gmt":"2025-10-16T18:50:23","slug":"woche-3-2","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2025\/10\/15\/woche-3-2\/","title":{"rendered":"Woche 3"},"content":{"rendered":"<p align=\"justify\">Und schon ist Woche 3 vorbei. Man sieht, da\u00df Europa echt klein ist, weil wir sind in der Woche gerade mal knappe 1200km gefahren. Das haben wir an einem Fahrtag in den USA schon an einem Tag geschafft. Aber es hat ja auch was Sch\u00f6nes nicht so lange Fahren zu m\u00fcssen.<\/p>\n<p> <iframe loading=\"lazy\" height=\"600\" src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1Bs967m7lm-YQQA4wDKrskIWDoQ-vczg&amp;ehbc=2E312F\" width=\"800\"><\/iframe>   <\/p>\n<p align=\"justify\">In der dritten Woche sind wir quer durch Frankreich gefahren und einiges wieder zur\u00fcck, dieses mal auf der spanischen Seite der Pyren\u00e4en. H\u00f6hepunkte waren dabei:<\/p>\n<ul>\n<li>\n<div align=\"justify\">Mehrere Tage Canal du Midi<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Toulouse<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Lourdes<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Biarritz<\/div>\n<\/li>\n<li>\n<div align=\"justify\">die Atlantikk\u00fcste<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Bilbao<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Las Bardena Reales<\/div>\n<\/li>\n<li>\n<div align=\"justify\">Saragossa <\/div>\n<\/li>\n<\/ul>\n<p>Die vierte und letzte vollst\u00e4ndige Woche wird einen Spanienteil und einen Heimreiseteil haben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Und schon ist Woche 3 vorbei. Man sieht, da\u00df Europa echt klein ist, weil wir sind in der Woche gerade mal knappe 1200km gefahren. Das haben wir an einem Fahrtag in den USA schon an einem Tag geschafft. Aber es hat ja auch was Sch\u00f6nes nicht so lange Fahren zu m\u00fcssen. In der dritten Woche sind wir quer durch Frankreich gefahren und einiges wieder zur\u00fcck, dieses mal auf der spanischen Seite der Pyren\u00e4en. H\u00f6hepunkte waren dabei: Mehrere Tage Canal du Midi Toulouse Lourdes Biarritz die Atlantikk\u00fcste Bilbao Las Bardena Reales Saragossa Die vierte und letzte vollst\u00e4ndige Woche wird einen Spanienteil<\/p>\n","protected":false},"author":1,"featured_media":15516,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-39249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aroundtheworld"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/39249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=39249"}],"version-history":[{"count":1,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/39249\/revisions"}],"predecessor-version":[{"id":39250,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/39249\/revisions\/39250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/15516"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=39249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=39249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=39249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}