{"id":590,"date":"2015-10-05T04:46:00","date_gmt":"2015-10-05T04:46:00","guid":{"rendered":"https:\/\/blog.chbworld.net\/index.php\/2015\/10\/05\/quiz-der-anzeigen\/"},"modified":"2024-04-20T17:24:48","modified_gmt":"2024-04-20T16:24:48","slug":"quiz-der-anzeigen","status":"publish","type":"post","link":"https:\/\/blog.chbworld.net\/index.php\/2015\/10\/05\/quiz-der-anzeigen\/","title":{"rendered":"Quiz der Anzeigen"},"content":{"rendered":"<p align=\"justify\">Wenn man hier auf der Autobahn f\u00e4hrt, gibt es jede Menge von Anzeigetafeln, die im Unfallfall sagen was los ist und was man tun kann, oder die im Normalfall schlaue Spr\u00fcche schreiben. Wie \u2018lasse niemals ein Kind alleine in einem Auto\u2019, oder \u2018Angurten ist Gesetz\u2019. Einige schreiben das auch ein wenig spannender, wie \u2018W\u00fcrdest Du Dein Leben darauf verwetten, da\u00df Dich der LKW Fahrer gesehen hat?\u2019<\/p>\n<p align=\"justify\">Heute habe ich aber einen f\u00fcr mich neuen Text gesehen: <\/p>\n<blockquote>\n<p align=\"justify\">\u201cSilver Alert\u201d, gefolgt von einer Fahrzeugbescheibung, einem Kennzeichen und einer Telefonnummer.<\/p>\n<\/blockquote>\n<p align=\"justify\">Daher die Frage an Euch: Was wollen die von mir???<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn man hier auf der Autobahn f\u00e4hrt, gibt es jede Menge von Anzeigetafeln, die im Unfallfall sagen was los ist und was man tun kann, oder die im Normalfall schlaue Spr\u00fcche schreiben. Wie \u2018lasse niemals ein Kind alleine in einem Auto\u2019, oder \u2018Angurten ist Gesetz\u2019. Einige schreiben das auch ein wenig spannender, wie \u2018W\u00fcrdest Du Dein Leben darauf verwetten, da\u00df Dich der LKW Fahrer gesehen hat?\u2019 Heute habe ich aber einen f\u00fcr mich neuen Text gesehen: \u201cSilver Alert\u201d, gefolgt von einer Fahrzeugbescheibung, einem Kennzeichen und einer Telefonnummer. Daher die Frage an Euch: Was wollen die von mir???<\/p>\n","protected":false},"author":1,"featured_media":20095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aroundtheworld"],"_links":{"self":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":1,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"predecessor-version":[{"id":16890,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/posts\/590\/revisions\/16890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media\/20095"}],"wp:attachment":[{"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.chbworld.net\/index.php\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}